{"id":613,"date":"2013-11-19T09:40:48","date_gmt":"2013-11-19T14:40:48","guid":{"rendered":"http:\/\/freestuffbymail.org\/dailyfreebies\/?p=613"},"modified":"2013-11-19T09:40:48","modified_gmt":"2013-11-19T14:40:48","slug":"free-hr-green-2014-calendar","status":"publish","type":"post","link":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/","title":{"rendered":"Free HR Green 2014 Calendar"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" alt=\"Free 2014 Calendar\" src=\"http:\/\/screencloud.net\/img\/screenshots\/f1977744489377d0b4dd7a63a36a4d0d.png\" width=\"235\" height=\"153\" \/><\/p>\n<p style=\"text-align: center;\">Grab your free calendar from HR Green, includes all major holidays and more!<\/p>\n<h3 style=\"text-align: center;\"><a title=\"Free Calendar\" href=\"http:\/\/www.hrgreen.com\/aboutUS\/contactUs_HRGreenCalendar.aspx\" target=\"_blank\">&gt;&gt; Click Here For The Free 2014 Calendar &lt;&lt;<\/a><\/h3>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Grab your free calendar from HR Green, includes all major holidays and more! &gt;&gt; Click Here For The Free 2014 Calendar &lt;&lt;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1314,406,22,8,247],"class_list":["post-613","post","type-post","status-publish","format-standard","hentry","category-free-samples","tag-1314","tag-calendar","tag-free","tag-freebie","tag-freebies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Free HR Green 2014 Calendar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Free HR Green 2014 Calendar\" \/>\n<meta property=\"og:description\" content=\"Grab your free calendar from HR Green, includes all major holidays and more! &gt;&gt; Click Here For The Free 2014 Calendar &lt;&lt;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/\" \/>\n<meta property=\"og:site_name\" content=\"American Freebies\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/freebiesandfreestuff\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-19T14:40:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/screencloud.net\/img\/screenshots\/f1977744489377d0b4dd7a63a36a4d0d.png\" \/>\n<meta name=\"author\" content=\"freebienick\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"freebienick\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/\"},\"author\":{\"name\":\"freebienick\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/person\\\/ce10d3c9e7706f9d10c45f6bc014ebce\"},\"headline\":\"Free HR Green 2014 Calendar\",\"datePublished\":\"2013-11-19T14:40:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/\"},\"wordCount\":27,\"publisher\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/screencloud.net\\\/img\\\/screenshots\\\/f1977744489377d0b4dd7a63a36a4d0d.png\",\"keywords\":[\"2014\",\"calendar\",\"Free\",\"freebie\",\"Freebies\"],\"articleSection\":[\"Free Samples\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/\",\"name\":\"Free HR Green 2014 Calendar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/screencloud.net\\\/img\\\/screenshots\\\/f1977744489377d0b4dd7a63a36a4d0d.png\",\"datePublished\":\"2013-11-19T14:40:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/#primaryimage\",\"url\":\"http:\\\/\\\/screencloud.net\\\/img\\\/screenshots\\\/f1977744489377d0b4dd7a63a36a4d0d.png\",\"contentUrl\":\"http:\\\/\\\/screencloud.net\\\/img\\\/screenshots\\\/f1977744489377d0b4dd7a63a36a4d0d.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-hr-green-2014-calendar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Free HR Green 2014 Calendar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#website\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/\",\"name\":\"American Freebies\",\"description\":\"Free Stuff By Mail\",\"publisher\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#organization\",\"name\":\"American Freebies\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/american-freebies.png\",\"contentUrl\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/american-freebies.png\",\"width\":500,\"height\":500,\"caption\":\"American Freebies\"},\"image\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/freebiesandfreestuff\",\"https:\\\/\\\/pin.it\\\/2YUqKLj\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/person\\\/ce10d3c9e7706f9d10c45f6bc014ebce\",\"name\":\"freebienick\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g\",\"caption\":\"freebienick\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Free HR Green 2014 Calendar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/","og_locale":"en_US","og_type":"article","og_title":"Free HR Green 2014 Calendar","og_description":"Grab your free calendar from HR Green, includes all major holidays and more! &gt;&gt; Click Here For The Free 2014 Calendar &lt;&lt;","og_url":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/","og_site_name":"American Freebies","article_publisher":"https:\/\/www.facebook.com\/freebiesandfreestuff","article_published_time":"2013-11-19T14:40:48+00:00","og_image":[{"url":"http:\/\/screencloud.net\/img\/screenshots\/f1977744489377d0b4dd7a63a36a4d0d.png","type":"","width":"","height":""}],"author":"freebienick","twitter_card":"summary_large_image","twitter_misc":{"Written by":"freebienick"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/#article","isPartOf":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/"},"author":{"name":"freebienick","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/person\/ce10d3c9e7706f9d10c45f6bc014ebce"},"headline":"Free HR Green 2014 Calendar","datePublished":"2013-11-19T14:40:48+00:00","mainEntityOfPage":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/"},"wordCount":27,"publisher":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#organization"},"image":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/#primaryimage"},"thumbnailUrl":"http:\/\/screencloud.net\/img\/screenshots\/f1977744489377d0b4dd7a63a36a4d0d.png","keywords":["2014","calendar","Free","freebie","Freebies"],"articleSection":["Free Samples"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/","name":"Free HR Green 2014 Calendar","isPartOf":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#website"},"primaryImageOfPage":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/#primaryimage"},"image":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/#primaryimage"},"thumbnailUrl":"http:\/\/screencloud.net\/img\/screenshots\/f1977744489377d0b4dd7a63a36a4d0d.png","datePublished":"2013-11-19T14:40:48+00:00","breadcrumb":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/#primaryimage","url":"http:\/\/screencloud.net\/img\/screenshots\/f1977744489377d0b4dd7a63a36a4d0d.png","contentUrl":"http:\/\/screencloud.net\/img\/screenshots\/f1977744489377d0b4dd7a63a36a4d0d.png"},{"@type":"BreadcrumbList","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-hr-green-2014-calendar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/freestuffbymail.org\/dailyfreebies"},{"@type":"ListItem","position":2,"name":"Free HR Green 2014 Calendar"}]},{"@type":"WebSite","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#website","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/","name":"American Freebies","description":"Free Stuff By Mail","publisher":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freestuffbymail.org\/dailyfreebies\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#organization","name":"American Freebies","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/logo\/image\/","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2022\/04\/american-freebies.png","contentUrl":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2022\/04\/american-freebies.png","width":500,"height":500,"caption":"American Freebies"},"image":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/freebiesandfreestuff","https:\/\/pin.it\/2YUqKLj"]},{"@type":"Person","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/person\/ce10d3c9e7706f9d10c45f6bc014ebce","name":"freebienick","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g","caption":"freebienick"}}]}},"_links":{"self":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/posts\/613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/comments?post=613"}],"version-history":[{"count":0,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/posts\/613\/revisions"}],"wp:attachment":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/media?parent=613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/categories?post=613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/tags?post=613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}