{"id":31,"date":"2010-08-27T06:57:09","date_gmt":"2010-08-27T11:57:09","guid":{"rendered":"http:\/\/freestuffbymail.org\/dailyfreebies\/?p=31"},"modified":"2010-08-27T06:57:09","modified_gmt":"2010-08-27T11:57:09","slug":"free-nikwax-leather-fabric-proof-sample","status":"publish","type":"post","link":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/","title":{"rendered":"Free Nikwax Leather &#038; Fabric Proof Sample"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-32\" title=\"nikwax\" src=\"http:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2010\/08\/nikwax-131x300.jpg\" alt=\"nikwax sample\" width=\"131\" height=\"300\" srcset=\"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2010\/08\/nikwax-131x300.jpg 131w, https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2010\/08\/nikwax.jpg 189w\" sizes=\"auto, (max-width: 131px) 100vw, 131px\" \/><\/p>\n<p style=\"text-align: center;\">Correctly answer a quiz on a Nikwax web site and get this free sample of Nikwax Fabric &amp; Leather Proof.<\/p>\n<h2 style=\"text-align: center;\"><a title=\"Nikwax Sample\" href=\"http:\/\/www.nikwax.com\/en-gb\/webquiz\/index.php?dm_i=AWA,7OJO,1ST7AI,JEYC,1\" target=\"_blank\">&gt;&gt; Get The Free Nikwax Fabric And Leather Proof Sample &lt;&lt;<\/a><\/h2>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Correctly answer a quiz on a Nikwax web site and get this free sample of Nikwax Fabric &amp; Leather Proof. &gt;&gt; Get The Free Nikwax Fabric And Leather Proof Sample &lt;&lt;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[99,22,65,8,98,94,95,96,97,82],"class_list":["post-31","post","type-post","status-publish","format-standard","hentry","category-free-samples","tag-fabric","tag-free","tag-free-sample","tag-freebie","tag-leather","tag-leather-fabric","tag-nikwax","tag-proof","tag-quiz","tag-shopping"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Free Nikwax Leather &amp; Fabric Proof Sample<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Free Nikwax Leather &amp; Fabric Proof Sample\" \/>\n<meta property=\"og:description\" content=\"Correctly answer a quiz on a Nikwax web site and get this free sample of Nikwax Fabric &amp; Leather Proof. &gt;&gt; Get The Free Nikwax Fabric And Leather Proof Sample &lt;&lt;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/\" \/>\n<meta property=\"og:site_name\" content=\"American Freebies\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/freebiesandfreestuff\" \/>\n<meta property=\"article:published_time\" content=\"2010-08-27T11:57:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2010\/08\/nikwax-131x300.jpg\" \/>\n<meta name=\"author\" content=\"freebienick\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"freebienick\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/\"},\"author\":{\"name\":\"freebienick\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/person\\\/ce10d3c9e7706f9d10c45f6bc014ebce\"},\"headline\":\"Free Nikwax Leather &#038; Fabric Proof Sample\",\"datePublished\":\"2010-08-27T11:57:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/\"},\"wordCount\":39,\"publisher\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/nikwax-131x300.jpg\",\"keywords\":[\"Fabric\",\"Free\",\"free sample\",\"freebie\",\"Leather\",\"leather fabric\",\"nikwax\",\"proof\",\"quiz\",\"Shopping\"],\"articleSection\":[\"Free Samples\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/\",\"name\":\"Free Nikwax Leather & Fabric Proof Sample\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/nikwax-131x300.jpg\",\"datePublished\":\"2010-08-27T11:57:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/#primaryimage\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/nikwax.jpg\",\"contentUrl\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/nikwax.jpg\",\"width\":\"189\",\"height\":\"431\",\"caption\":\"nikwax sample\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-nikwax-leather-fabric-proof-sample\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Free Nikwax Leather &#038; Fabric Proof Sample\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#website\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/\",\"name\":\"American Freebies\",\"description\":\"Free Stuff By Mail\",\"publisher\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#organization\",\"name\":\"American Freebies\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/american-freebies.png\",\"contentUrl\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/american-freebies.png\",\"width\":500,\"height\":500,\"caption\":\"American Freebies\"},\"image\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/freebiesandfreestuff\",\"https:\\\/\\\/pin.it\\\/2YUqKLj\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/person\\\/ce10d3c9e7706f9d10c45f6bc014ebce\",\"name\":\"freebienick\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g\",\"caption\":\"freebienick\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Free Nikwax Leather & Fabric Proof Sample","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/","og_locale":"en_US","og_type":"article","og_title":"Free Nikwax Leather & Fabric Proof Sample","og_description":"Correctly answer a quiz on a Nikwax web site and get this free sample of Nikwax Fabric &amp; Leather Proof. &gt;&gt; Get The Free Nikwax Fabric And Leather Proof Sample &lt;&lt;","og_url":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/","og_site_name":"American Freebies","article_publisher":"https:\/\/www.facebook.com\/freebiesandfreestuff","article_published_time":"2010-08-27T11:57:09+00:00","og_image":[{"url":"http:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2010\/08\/nikwax-131x300.jpg","type":"","width":"","height":""}],"author":"freebienick","twitter_card":"summary_large_image","twitter_misc":{"Written by":"freebienick"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/#article","isPartOf":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/"},"author":{"name":"freebienick","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/person\/ce10d3c9e7706f9d10c45f6bc014ebce"},"headline":"Free Nikwax Leather &#038; Fabric Proof Sample","datePublished":"2010-08-27T11:57:09+00:00","mainEntityOfPage":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/"},"wordCount":39,"publisher":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#organization"},"image":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/#primaryimage"},"thumbnailUrl":"http:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2010\/08\/nikwax-131x300.jpg","keywords":["Fabric","Free","free sample","freebie","Leather","leather fabric","nikwax","proof","quiz","Shopping"],"articleSection":["Free Samples"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/","name":"Free Nikwax Leather & Fabric Proof Sample","isPartOf":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#website"},"primaryImageOfPage":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/#primaryimage"},"image":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/#primaryimage"},"thumbnailUrl":"http:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2010\/08\/nikwax-131x300.jpg","datePublished":"2010-08-27T11:57:09+00:00","breadcrumb":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/#primaryimage","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2010\/08\/nikwax.jpg","contentUrl":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2010\/08\/nikwax.jpg","width":"189","height":"431","caption":"nikwax sample"},{"@type":"BreadcrumbList","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-nikwax-leather-fabric-proof-sample\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/freestuffbymail.org\/dailyfreebies"},{"@type":"ListItem","position":2,"name":"Free Nikwax Leather &#038; Fabric Proof Sample"}]},{"@type":"WebSite","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#website","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/","name":"American Freebies","description":"Free Stuff By Mail","publisher":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freestuffbymail.org\/dailyfreebies\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#organization","name":"American Freebies","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/logo\/image\/","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2022\/04\/american-freebies.png","contentUrl":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2022\/04\/american-freebies.png","width":500,"height":500,"caption":"American Freebies"},"image":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/freebiesandfreestuff","https:\/\/pin.it\/2YUqKLj"]},{"@type":"Person","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/person\/ce10d3c9e7706f9d10c45f6bc014ebce","name":"freebienick","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g","caption":"freebienick"}}]}},"_links":{"self":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/posts\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":0,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/posts\/31\/revisions"}],"wp:attachment":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/media?parent=31"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/categories?post=31"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/tags?post=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}