{"id":301,"date":"2011-04-19T11:42:02","date_gmt":"2011-04-19T16:42:02","guid":{"rendered":"http:\/\/freestuffbymail.org\/dailyfreebies\/?p=301"},"modified":"2011-04-19T11:42:02","modified_gmt":"2011-04-19T16:42:02","slug":"free-smoothie-from-cosi","status":"publish","type":"post","link":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/","title":{"rendered":"Free Smoothie From Cosi"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-302\" title=\"free smoothie\" src=\"http:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2011\/04\/freesmoothie.jpg\" alt=\"free smoothie\" width=\"296\" height=\"382\" srcset=\"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2011\/04\/freesmoothie.jpg 296w, https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2011\/04\/freesmoothie-232x300.jpg 232w\" sizes=\"auto, (max-width: 296px) 100vw, 296px\" \/><\/p>\n<p style=\"text-align: center;\">Cosi is offering a free smoothie if you visit any Cosi location on Apr, 20th from 2-4pm. You can choose from Blueberry Pomegranate, Strawberry, Green Tea, and Mango.<\/p>\n<h2 style=\"text-align: center;\"><a title=\"Free Smoothies\" href=\"http:\/\/getcosi.com\/cprmlpc.html\" target=\"_blank\">&gt;&gt; Click Here For Free Smoothie &lt;&lt;<\/a><\/h2>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Cosi is offering a free smoothie if you visit any Cosi location on Apr, 20th from 2-4pm. You can choose from Blueberry Pomegranate, Strawberry, Green Tea, and Mango. &gt;&gt; Click Here For Free Smoothie &lt;&lt;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[407,824,829,45,823,827,22,8,247,44,581,822,825,563,828,41,830,826,213],"class_list":["post-301","post","type-post","status-publish","format-standard","hentry","category-free-samples","tag-407","tag-4pm","tag-apr","tag-beverages","tag-blueberry","tag-cosi","tag-free","tag-freebie","tag-freebies","tag-fruit","tag-green","tag-green-tea","tag-mango","tag-offer","tag-pomegranate","tag-smoothie","tag-smoothies","tag-strawberry","tag-stuff"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Free Smoothie From Cosi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Free Smoothie From Cosi\" \/>\n<meta property=\"og:description\" content=\"Cosi is offering a free smoothie if you visit any Cosi location on Apr, 20th from 2-4pm. You can choose from Blueberry Pomegranate, Strawberry, Green Tea, and Mango. &gt;&gt; Click Here For Free Smoothie &lt;&lt;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/\" \/>\n<meta property=\"og:site_name\" content=\"American Freebies\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/freebiesandfreestuff\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-19T16:42:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2011\/04\/freesmoothie.jpg\" \/>\n<meta name=\"author\" content=\"freebienick\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"freebienick\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/\"},\"author\":{\"name\":\"freebienick\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/person\\\/ce10d3c9e7706f9d10c45f6bc014ebce\"},\"headline\":\"Free Smoothie From Cosi\",\"datePublished\":\"2011-04-19T16:42:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/\"},\"wordCount\":42,\"publisher\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/freesmoothie.jpg\",\"keywords\":[\"2011\",\"4pm\",\"Apr\",\"Beverages\",\"blueberry\",\"Cosi\",\"Free\",\"freebie\",\"Freebies\",\"Fruit\",\"Green\",\"green tea\",\"mango\",\"offer\",\"Pomegranate\",\"smoothie\",\"Smoothies\",\"strawberry\",\"Stuff\"],\"articleSection\":[\"Free Samples\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/\",\"name\":\"Free Smoothie From Cosi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/freesmoothie.jpg\",\"datePublished\":\"2011-04-19T16:42:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/freesmoothie.jpg\",\"contentUrl\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/freesmoothie.jpg\",\"width\":\"296\",\"height\":\"382\",\"caption\":\"free smoothie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/free-smoothie-from-cosi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Free Smoothie From Cosi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#website\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/\",\"name\":\"American Freebies\",\"description\":\"Free Stuff By Mail\",\"publisher\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#organization\",\"name\":\"American Freebies\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/american-freebies.png\",\"contentUrl\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/american-freebies.png\",\"width\":500,\"height\":500,\"caption\":\"American Freebies\"},\"image\":{\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/freebiesandfreestuff\",\"https:\\\/\\\/pin.it\\\/2YUqKLj\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/freestuffbymail.org\\\/dailyfreebies\\\/#\\\/schema\\\/person\\\/ce10d3c9e7706f9d10c45f6bc014ebce\",\"name\":\"freebienick\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g\",\"caption\":\"freebienick\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Free Smoothie From Cosi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/","og_locale":"en_US","og_type":"article","og_title":"Free Smoothie From Cosi","og_description":"Cosi is offering a free smoothie if you visit any Cosi location on Apr, 20th from 2-4pm. You can choose from Blueberry Pomegranate, Strawberry, Green Tea, and Mango. &gt;&gt; Click Here For Free Smoothie &lt;&lt;","og_url":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/","og_site_name":"American Freebies","article_publisher":"https:\/\/www.facebook.com\/freebiesandfreestuff","article_published_time":"2011-04-19T16:42:02+00:00","og_image":[{"url":"http:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2011\/04\/freesmoothie.jpg","type":"","width":"","height":""}],"author":"freebienick","twitter_card":"summary_large_image","twitter_misc":{"Written by":"freebienick"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/#article","isPartOf":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/"},"author":{"name":"freebienick","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/person\/ce10d3c9e7706f9d10c45f6bc014ebce"},"headline":"Free Smoothie From Cosi","datePublished":"2011-04-19T16:42:02+00:00","mainEntityOfPage":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/"},"wordCount":42,"publisher":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#organization"},"image":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/#primaryimage"},"thumbnailUrl":"http:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2011\/04\/freesmoothie.jpg","keywords":["2011","4pm","Apr","Beverages","blueberry","Cosi","Free","freebie","Freebies","Fruit","Green","green tea","mango","offer","Pomegranate","smoothie","Smoothies","strawberry","Stuff"],"articleSection":["Free Samples"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/","name":"Free Smoothie From Cosi","isPartOf":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#website"},"primaryImageOfPage":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/#primaryimage"},"image":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/#primaryimage"},"thumbnailUrl":"http:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2011\/04\/freesmoothie.jpg","datePublished":"2011-04-19T16:42:02+00:00","breadcrumb":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/#primaryimage","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2011\/04\/freesmoothie.jpg","contentUrl":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2011\/04\/freesmoothie.jpg","width":"296","height":"382","caption":"free smoothie"},{"@type":"BreadcrumbList","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/free-smoothie-from-cosi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/freestuffbymail.org\/dailyfreebies"},{"@type":"ListItem","position":2,"name":"Free Smoothie From Cosi"}]},{"@type":"WebSite","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#website","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/","name":"American Freebies","description":"Free Stuff By Mail","publisher":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/freestuffbymail.org\/dailyfreebies\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#organization","name":"American Freebies","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/logo\/image\/","url":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2022\/04\/american-freebies.png","contentUrl":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-content\/uploads\/2022\/04\/american-freebies.png","width":500,"height":500,"caption":"American Freebies"},"image":{"@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/freebiesandfreestuff","https:\/\/pin.it\/2YUqKLj"]},{"@type":"Person","@id":"https:\/\/freestuffbymail.org\/dailyfreebies\/#\/schema\/person\/ce10d3c9e7706f9d10c45f6bc014ebce","name":"freebienick","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/feca070697c8c3720ed11f84a47f7f2c97ef5c95796272703da5d1181c7f2193?s=96&r=g","caption":"freebienick"}}]}},"_links":{"self":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/posts\/301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/comments?post=301"}],"version-history":[{"count":0,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/posts\/301\/revisions"}],"wp:attachment":[{"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/media?parent=301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/categories?post=301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/freestuffbymail.org\/dailyfreebies\/wp-json\/wp\/v2\/tags?post=301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}